{"id":36477,"date":"2018-09-06T00:04:11","date_gmt":"2018-09-06T04:04:11","guid":{"rendered":"https:\/\/explora.cl\/blog\/2018\/09\/06\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/"},"modified":"2019-05-16T02:04:01","modified_gmt":"2019-05-16T02:04:01","slug":"colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande","status":"publish","type":"post","link":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/","title":{"rendered":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-36475\" src=\"https:\/\/explora.cl\/wp-content\/uploads\/2018\/09\/header.jpg\" alt=\"header\" width=\"1389\" height=\"663\" \/><br \/>\n<strong><em>*II Encuentro Intercultural Escolar de Ciencia y Tecnolog\u00eda, organizado por el PAR Explora de CONICYT Tarapac\u00e1, reuni\u00f3 a j\u00f3venes estudiantes de Chile, Per\u00fa y Bolivia para compartir y aprender de experiencias en ciencias.<\/em><\/strong><br \/>\nEl pasado lunes 3 y martes 4 de septiembre, 150 j\u00f3venes estudiantes de Per\u00fa, Bolivia y de la regi\u00f3n de Tarapac\u00e1 se reunieron en la comuna de Colchane, provincia del Tamarugal, con motivo de compartir experiencias en ciencia y tecnolog\u00eda, como parte del II Encuentro Intercultural Escolar de Ciencia y Tecnolog\u00eda Colchane 2018, el cual fue organizado por el PAR Explora de CONICYT Tarapac\u00e1, proyecto ejecutado por la Corporaci\u00f3n de Desarrollo de Tarapac\u00e1.<br \/>\nLa iniciativa de integraci\u00f3n cient\u00edfica y tecnol\u00f3gica parti\u00f3 en horas de la tarde del lunes con el participaci\u00f3n del Centro de Capacitaci\u00f3n Laboral de Iquique, el Colegio Academia Tarapac\u00e1, el Colegio Espa\u00f1a, el Colegio Hispano Italiano, el Colegio Humberstone, el Colegio Academia Iquique, el Colegio Little College, el Colegio Kronos de Alto Hospicio, la Escuela de Soga de Huara y el Liceo G- 105 de Huara. Adem\u00e1s, cont\u00f3 con la participaci\u00f3n internacional de Colegio San Mart\u00edn de Porres de Tacna-Per\u00fa y de la Unidad Educativa Sim\u00f3n Bolivar de Pisiga Bolivar de Bolivia.<br \/>\nComo parte del Encuentro se desarroll\u00f3 una Feria Cient\u00edfica en el Liceo T\u00e9cnico Profesional de Colchane y en forma paralela cont\u00f3 con la realizaci\u00f3n de cinco actividades paralelas realizadas: el \u201cTaller de dermocosm\u00e9tica andina\u201d, impartido por la Bioqu\u00edmica y Doctora en Biotecnolog\u00eda, Carolina Klagges, quien ense\u00f1\u00f3 a hacer jabones y cremas; la charla \u201cEl patrimonio sonoro en Tarapac\u00e1, un legado transfronterizo\u201d, impartida por la Historiadora e Investigadora del Centro de Investigaciones Patrimoniales de la Universidad de Tarapac\u00e1, Nicole Cort\u00e9s; la charla-taller \u201cBiodiversidad Costera de Tarapac\u00e1\u201d, impartida por la Bi\u00f3loga Marina, Magister en gesti\u00f3n ambiental y asesora cient\u00edfica del PAR Explora de CONICYT Tarapac\u00e1, Paula Salinas; la charla-taller \u201cRob\u00f3tica b\u00e1sica para la comunidad\u201d, impartida por el acad\u00e9mico de la UTA Sede Iquique Carlos Oyarce, y finalmente una charla sobre ciencia andina, impartida por el representante del Instituto de Ciencia, Cultura y Tecnolog\u00eda Andina (ICCYTA), Cornelio Chipana.<br \/>\nLa actividad cont\u00f3 con la presencia del Intendente Miguel \u00c1ngel Quezada; del Gobernador de la Provincia del Tamarugal, Luis Tobar; del Seremi de Educaci\u00f3n, Natan Olivos; del Alcalde de Colchane, Javier Garc\u00eda, del Gerente General de la Corporaci\u00f3n de Desarrollo Tarapac\u00e1, Rodrigo Guagama, quienes junto a ni\u00f1os, ni\u00f1as y profesores de Chile, Per\u00fa y Bolivia pudieron aprender de la energ\u00eda solar, los fertilizante org\u00e1nicos con lombrices, de filtros para el agua, preparaci\u00f3n de ung\u00fcentos medicinales, mec\u00e1nica automotriz y rob\u00f3tica, entro otros temas de gran inter\u00e9s.<br \/>\nEl Gerente General de la Corporaci\u00f3n de Desarrollo de Tarapac\u00e1, Rodrigo Guagama, precis\u00f3 que \u201cla Corporaci\u00f3n Tarapac\u00e1 tiene un compromiso, a trav\u00e9s del Proyecto Asociativo Regional Explora de CONICYT, que es llegar a toda la regi\u00f3n, especialmente a las comunas rurales como Colchane para promover una cultura cient\u00edfica y colaborativa, as\u00ed crear j\u00f3venes m\u00e1s participativos con sus comunidades\u201d. Adem\u00e1s destac\u00f3, \u201cque uno de los objetivo de la Corporaci\u00f3n es avanzar y fomentar la formaci\u00f3n de capital humano, fortaleciendo la base cient\u00edfica y tecnol\u00f3gica de los estudiantes nuestra regi\u00f3n\u201d.<br \/>\n\u00c9ste evento \u00fanico de integraci\u00f3n cient\u00edfica del norte grande tuvo como eje principal la interculturalidad y este a\u00f1o fue apoyado por la Seremi de Educaci\u00f3n de Tarapac\u00e1. Por su parte, Natan Olivos, Seremi de Educaci\u00f3n, relev\u00f3 la convocatoria y los trabajos presentados. \u201cEl encuentro intercultural de Ciencia y Tecnolog\u00eda Escolar ha reunido una importante cantidad de proyectos cient\u00edficos de 3 pa\u00edses, Per\u00fa, Bolivia y Chile. Junto al Intendente Miguel \u00c1ngel Quezada visitamos los stands y pudimos conocer iniciativas del \u00e1rea de la rob\u00f3tica, bot\u00e1nica, biofertilizantes, energ\u00eda, etc (\u2026) Nuestro Presidente lo ha mandatado, los ni\u00f1os primero es nuestra directriz como Gobierno y la calidad es nuestro mandato en Educaci\u00f3n\u201d, acot\u00f3.<br \/>\nEl Intendente Regional de Tarapac\u00e1, Miguel \u00c1ngel Quezada felicit\u00f3 la iniciativa de integraci\u00f3n y se mostr\u00f3 emocionado por el desarrollo de la actividad, precisando que \u201cestoy contento y orgulloso de ustedes y espero que esto sea un \u00e9xito, ya que esto no puede quedar en s\u00f3lo un segundo encuentro\u201d y comprometi\u00f3 el apoyo del Gobierno para que esta iniciativa siga adelante en la tierra de los aymaras, que es Colchane.<br \/>\nColaboradores<br \/>\nPara el desarrollo de este evento el PAR Explora de CONICYT Tarapac\u00e1 reconoci\u00f3 el trabajo conjunto con Liceo T\u00e9cnico Profesional de Colchane, con la Municipalidad de Colchane y con la Seremi de Educaci\u00f3n. Adem\u00e1s de agradecer el apoyo y la participaci\u00f3n de la Universidad de Tarapac\u00e1 sede Iquique, de la CONADI y de los establecimientos educacionales participantes.<br \/>\nEste encuentro se marca como un importante hito para la integraci\u00f3n social, cient\u00edfica y tecnol\u00f3gica en el norte de Chile.<br \/>\n<img decoding=\"async\" class=\" size-full wp-image-36476\" src=\"https:\/\/explora.cl\/wp-content\/uploads\/2018\/09\/colchane_collage.jpg\" alt=\"colchane collage\" width=\"1080\" height=\"1080\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*II Encuentro Intercultural Escolar de Ciencia y Tecnolog\u00eda, organizado por el PAR Explora de CONICYT Tarapac\u00e1, reuni\u00f3 a j\u00f3venes estudiantes de Chile, Per\u00fa y Bolivia para compartir y aprender de experiencias en ciencias. El pasado lunes 3 y martes 4 de septiembre, 150 j\u00f3venes estudiantes de Per\u00fa, Bolivia y de la regi\u00f3n de Tarapac\u00e1 se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37280,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-36477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"*II Encuentro Intercultural Escolar de Ciencia y Tecnolog\u00eda, organizado por el PAR Explora de CONICYT Tarapac\u00e1, reuni\u00f3 a j\u00f3venes estudiantes de Chile, Per\u00fa y Bolivia para compartir y aprender de experiencias en ciencias. El pasado lunes 3 y martes 4 de septiembre, 150 j\u00f3venes estudiantes de Per\u00fa, Bolivia y de la regi\u00f3n de Tarapac\u00e1 se [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Tarapaca\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-06T04:04:11+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T02:04:01+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande\",\"datePublished\":\"2018-09-06T04:04:11+00:00\",\"dateModified\":\"2019-05-16T02:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\"},\"wordCount\":861,\"image\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\",\"url\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\",\"name\":\"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg\",\"datePublished\":\"2018-09-06T04:04:11+00:00\",\"dateModified\":\"2019-05-16T02:04:01+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/tarapaca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/#website\",\"url\":\"https:\/\/explora.cl\/tarapaca\/\",\"name\":\"Tarapaca\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/tarapaca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/explora.cl\/tarapaca\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/","og_locale":"es_ES","og_type":"article","og_title":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca","og_description":"*II Encuentro Intercultural Escolar de Ciencia y Tecnolog\u00eda, organizado por el PAR Explora de CONICYT Tarapac\u00e1, reuni\u00f3 a j\u00f3venes estudiantes de Chile, Per\u00fa y Bolivia para compartir y aprender de experiencias en ciencias. El pasado lunes 3 y martes 4 de septiembre, 150 j\u00f3venes estudiantes de Per\u00fa, Bolivia y de la regi\u00f3n de Tarapac\u00e1 se [&hellip;]","og_url":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/","og_site_name":"Tarapaca","article_published_time":"2018-09-06T04:04:11+00:00","article_modified_time":"2019-05-16T02:04:01+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/"},"author":{"name":"webman","@id":"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande","datePublished":"2018-09-06T04:04:11+00:00","dateModified":"2019-05-16T02:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/"},"wordCount":861,"image":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/","url":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/","name":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande - Tarapaca","isPartOf":{"@id":"https:\/\/explora.cl\/tarapaca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg","datePublished":"2018-09-06T04:04:11+00:00","dateModified":"2019-05-16T02:04:01+00:00","author":{"@id":"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#primaryimage","url":"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg","contentUrl":"https:\/\/explora.cl\/tarapaca\/wp-content\/uploads\/sites\/3\/2018\/09\/colchane_collage.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/tarapaca\/colchane-se-transformo-en-la-cuna-de-la-integracion-cientifica-escolar-del-norte-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/tarapaca\/"},{"@type":"ListItem","position":2,"name":"Colchane se transform\u00f3 en la cuna de la integraci\u00f3n cient\u00edfica escolar del norte grande"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/tarapaca\/#website","url":"https:\/\/explora.cl\/tarapaca\/","name":"Tarapaca","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/tarapaca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/tarapaca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/explora.cl\/tarapaca\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/posts\/36477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/comments?post=36477"}],"version-history":[{"count":1,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/posts\/36477\/revisions"}],"predecessor-version":[{"id":38048,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/posts\/36477\/revisions\/38048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/media\/37280"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/media?parent=36477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/categories?post=36477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/tarapaca\/wp-json\/wp\/v2\/tags?post=36477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}