{"id":37228,"date":"2018-12-04T16:07:37","date_gmt":"2018-12-04T20:07:37","guid":{"rendered":"https:\/\/explora.cl\/rmsuroriente\/?p=37228"},"modified":"2019-05-20T17:31:16","modified_gmt":"2019-05-20T17:31:16","slug":"v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores","status":"publish","type":"post","link":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/","title":{"rendered":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-37232 alignleft\" src=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1-300x198.jpg 300w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1-768x508.jpg 768w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg 916w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Una intensa y emocionante jornada se vivi\u00f3 en la final del V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas del PAR Explora de CONICYT Regi\u00f3n Metropolitana Sur Oriente, realizada el martes de 6 de noviembre, en la Sala Dr. Hugo K. Sievers de la Facultad de Ciencias Veterinarias y Pecuarias (FAVET) de la Universidad de Chile.<br \/>\nEl encuentro cont\u00f3 con la presencia de las autoridades Fernando Fredes, Vicedecano de FAVET; Carola Guti\u00e9rrez Rosales, Directora del PAR Explora de CONICYT RM Sur Oriente; Carolina Valenzuela Subdirectora de Extensi\u00f3n y Comunicaci\u00f3n Estrat\u00e9gica de FAVET; Luis Alberto Raggi, Director del Centro Internacional de Estudios Andinos y Senador Universitario; Fanny Carrasco, Coordinadora de Lenguaje de la Red Educativa Cognita Chile y Gricel Gonz\u00e1lez, Coordinadora del torneo y encargada de Vinculaci\u00f3n Escolar del PAR Explora RM Sur Oriente.<br \/>\n<img decoding=\"async\" class=\"alignnone size-medium wp-image-37229 alignleft\" src=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-3-300x222.jpg\" alt=\"\" width=\"300\" height=\"222\" srcset=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-3-300x222.jpg 300w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-3-768x568.jpg 768w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-3.jpg 867w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Luego de un trio de debates con diferentes t\u00f3picos, el jurado compuesto por: Jaime Machuca, m\u00e9dico veterinario; Marlins Villanueva Trabajadora Social y Coordinadora Ejecutiva del PAR Explora de CONICYT RMSO; y el vicedecano Fernando Fredes, Doctor en Biociencias y Ciencias Agroalimentarias. Declar\u00f3 como ganador de la categor\u00eda \u201cdebatientes\u201d, al Equipo 1 del Colegio Pumahue; el segundo lugar fue conseguido por el equipo del Colegio Jos\u00e9 Joaqu\u00edn Prieto y el tercero, por los estudiantes del Colegio Pumahue Equipo 2. Mientras en la categor\u00eda \u201cinvestigadores\u201d, el primer lugar fue para el Equipo 1 del Colegio Pumahue; el segundo para el Equipo 3, del mismo Colegio Pumahue; y el tercero para el equipo de estudiantes del Colegio Patrona de Lourdes.<br \/>\nTras la premiaci\u00f3n, Fernando Fredes, se\u00f1al\u00f3 estar complacido con la calidad y nivel del debate: \u201cAunque no fui participe de la evoluci\u00f3n de ellos en los debates anteriores, s\u00e9 que han avanzado en forma espectacular. Han logrado demostrar inquietud, tuvieron buenas preguntas, buenas respuestas y debatieron con respeto (\u2026) Esta es una excelente iniciativa que permite llevar a terreno, la importancia de la ciencia para el desarrollo de un pa\u00eds y de su poblaci\u00f3n\u201d.<br \/>\n<img decoding=\"async\" class=\"alignnone size-medium wp-image-37230 alignleft\" src=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-5-300x204.jpg\" alt=\"\" width=\"300\" height=\"204\" srcset=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-5-300x204.jpg 300w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-5-768x523.jpg 768w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-5-474x324.jpg 474w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-foto-web-5.jpg 926w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Para llegar a ser finalistas del Torneo de Debate, los estudiantes se prepararon fuera de horario de clases, en talleres con sus profesores, reuniones con su equipo e investigando en casa. Adem\u00e1s, durante seis meses recibieron asesoramientos de argumentaci\u00f3n cient\u00edfica dirigidas por Gricel Gonz\u00e1lez. En dichas instancias, los estudiantes recibieron retroalimentaci\u00f3n por su desempe\u00f1o en debates anteriores y orientaci\u00f3n para su investigaci\u00f3n bibliogr\u00e1fica, que adem\u00e1s de paper cient\u00edficos, incluyeron consultas con cient\u00edficos expertos en distintas \u00e1reas.<br \/>\n\u201cEl proceso de crecimiento de ellos es impresionante, con este ejercicio se transforman. Ahora hay control de \u00edmpetu, control de emociones. Al principio hab\u00eda rabia, enojo y frustraci\u00f3n en los procesos de argumentaci\u00f3n, que fueron mejorando tras cada debate. Hoy d\u00eda eran j\u00f3venes que pod\u00edan enfrentarse a opiniones y criterios distintos, desde una templanza emocional que es admirable para su edad y tambi\u00e9n para el desarrollo de argumentaciones complejas\u201d, expres\u00f3 Gricel Gonz\u00e1lez.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-37233 alignleft\" src=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-fotoweb-1-300x202.jpg\" alt=\"\" width=\"300\" height=\"202\" srcset=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-fotoweb-1-300x202.jpg 300w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-fotoweb-1-768x518.jpg 768w, https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/debate-fotoweb-1.jpg 935w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>La estudiante Mariana Rojo, parte del equipo ganador en la categor\u00eda \u201cInvestigadores\u201d. Cont\u00f3 c\u00f3mo naci\u00f3 la idea de iniciarse en los torneos de debate: \u201cTodo parti\u00f3 porque nuestra profesora lleg\u00f3 este a\u00f1o incit\u00e1ndonos para entrar a debate. Entramos de manera voluntaria y cuando nos dimos cuenta que \u00e9ramos buenos, nos motivamos. Hay que dedicarle tiempo, organizar al grupo, estudiar, investigar y hacer un informe. Pero es s\u00faper entretenido\u201d.<br \/>\nPor su parte, Natalia Gordillo, estudiante del Colegio Patrona Se\u00f1ora de Lourdes, cont\u00f3 c\u00f3mo fue su experiencia en el torneo: \u201cAl inicio estaba muy asustada porque no sab\u00eda c\u00f3mo hacerlo, pero ahora creo que esto me va ayudar mucho en mi futuro. Lo pase s\u00faper bien, no niego que me puse nerviosa con las preguntas de los jueces.\u00a0 Pero fue divertido, aprend\u00ed cosas que nunca en la vida me hab\u00eda cuestionado y me encantar\u00eda repetir la experiencia\u201d, declar\u00f3.<br \/>\nLa Coordinadora de Lenguaje de la Red Educativa Cognita Chile, Fanny Carrasco, explic\u00f3 que el desarrollo de pensamiento cr\u00edtico y creativo que comprende el debate es una herramienta fundamental para los estudiantes: \u201cNosotros realizamos este a\u00f1o el segundo torneo de debate critico interno, con la ayuda de PAR Explora RM Sur Oriente. En los colegios Pumahue trabajamos muy fuertemente el debate critico en aula, es un modo de ser el pensamiento visible, que es esencial como competencia para este nuevo siglo\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una intensa y emocionante jornada se vivi\u00f3 en la final del V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas del PAR Explora de CONICYT Regi\u00f3n Metropolitana Sur Oriente, realizada el martes de 6 de noviembre, en la Sala Dr. Hugo K. Sievers de la Facultad de Ciencias Veterinarias y Pecuarias (FAVET) de la Universidad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37232,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-37228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Una intensa y emocionante jornada se vivi\u00f3 en la final del V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas del PAR Explora de CONICYT Regi\u00f3n Metropolitana Sur Oriente, realizada el martes de 6 de noviembre, en la Sala Dr. Hugo K. Sievers de la Facultad de Ciencias Veterinarias y Pecuarias (FAVET) de la Universidad [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"RM Sur Oriente\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-04T20:07:37+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:31:16+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"916\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores\",\"datePublished\":\"2018-12-04T20:07:37+00:00\",\"dateModified\":\"2019-05-20T17:31:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\"},\"wordCount\":760,\"publisher\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#organization\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\",\"url\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\",\"name\":\"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg\",\"datePublished\":\"2018-12-04T20:07:37+00:00\",\"dateModified\":\"2019-05-20T17:31:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg\",\"width\":916,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/rmsuroriente\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#website\",\"url\":\"https:\/\/explora.cl\/rmsuroriente\/\",\"name\":\"RM Sur Oriente\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"publisher\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/rmsuroriente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#organization\",\"name\":\"RM Sur Oriente\",\"url\":\"https:\/\/explora.cl\/rmsuroriente\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2025\/04\/cropped-LogoPAR_RMSO-Azul-UC.png\",\"contentUrl\":\"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2025\/04\/cropped-LogoPAR_RMSO-Azul-UC.png\",\"width\":411,\"height\":409,\"caption\":\"RM Sur Oriente\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/explora.cl\/rmsuroriente\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/","og_locale":"es_ES","og_type":"article","og_title":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente","og_description":"Una intensa y emocionante jornada se vivi\u00f3 en la final del V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas del PAR Explora de CONICYT Regi\u00f3n Metropolitana Sur Oriente, realizada el martes de 6 de noviembre, en la Sala Dr. Hugo K. Sievers de la Facultad de Ciencias Veterinarias y Pecuarias (FAVET) de la Universidad [&hellip;]","og_url":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/","og_site_name":"RM Sur Oriente","article_published_time":"2018-12-04T20:07:37+00:00","article_modified_time":"2019-05-20T17:31:16+00:00","og_image":[{"width":916,"height":606,"url":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/"},"author":{"name":"webman","@id":"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores","datePublished":"2018-12-04T20:07:37+00:00","dateModified":"2019-05-20T17:31:16+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/"},"wordCount":760,"publisher":{"@id":"https:\/\/explora.cl\/rmsuroriente\/#organization"},"image":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/","url":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/","name":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores - RM Sur Oriente","isPartOf":{"@id":"https:\/\/explora.cl\/rmsuroriente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg","datePublished":"2018-12-04T20:07:37+00:00","dateModified":"2019-05-20T17:31:16+00:00","breadcrumb":{"@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#primaryimage","url":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg","contentUrl":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2018\/12\/foto-debate-web-2-1.jpg","width":916,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/rmsuroriente\/v-torneo-escolar-de-debates-en-ciencias-y-tecnologias-ya-tiene-ganadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/rmsuroriente\/"},{"@type":"ListItem","position":2,"name":"V Torneo Escolar de Debates en Ciencias y Tecnolog\u00edas ya tiene ganadores"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/rmsuroriente\/#website","url":"https:\/\/explora.cl\/rmsuroriente\/","name":"RM Sur Oriente","description":"Otro sitio m\u00e1s de explora.cl","publisher":{"@id":"https:\/\/explora.cl\/rmsuroriente\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/rmsuroriente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/explora.cl\/rmsuroriente\/#organization","name":"RM Sur Oriente","url":"https:\/\/explora.cl\/rmsuroriente\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/logo\/image\/","url":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2025\/04\/cropped-LogoPAR_RMSO-Azul-UC.png","contentUrl":"https:\/\/explora.cl\/rmsuroriente\/wp-content\/uploads\/sites\/12\/2025\/04\/cropped-LogoPAR_RMSO-Azul-UC.png","width":411,"height":409,"caption":"RM Sur Oriente"},"image":{"@id":"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/rmsuroriente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/explora.cl\/rmsuroriente\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/posts\/37228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/comments?post=37228"}],"version-history":[{"count":1,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/posts\/37228\/revisions"}],"predecessor-version":[{"id":37567,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/posts\/37228\/revisions\/37567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/media\/37232"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/media?parent=37228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/categories?post=37228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/rmsuroriente\/wp-json\/wp\/v2\/tags?post=37228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}