{"id":32047,"date":"2014-08-28T00:00:00","date_gmt":"2014-08-28T04:00:00","guid":{"rendered":"https:\/\/explora.cl\/rmnorte\/blog\/2014\/08\/28\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/"},"modified":"2019-05-20T17:23:41","modified_gmt":"2019-05-20T17:23:41","slug":"tabla-periodica-interactiva-se-toma-colegio-verbo-divino","status":"publish","type":"post","link":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/","title":{"rendered":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-4974\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/08\/e4d5c44c5a496510a92bb496aa533f7c.jpg\" alt=\"\" width=\"1000\" height=\"675\" \/><\/p>\n<p>La Tabla Peri\u00f3dica Interactiva, muestra que ha recorrido gran parte de Chile, ya se encuentra en la Regi\u00f3n Metropolitana Norte donde visitar\u00e1 diferentes establecimientos educacionales y universidades.<\/p>\n<p>La itinerancia, que actualmente se encuentra en el Colegio Verbo Divino de Las Condes, busca acercar a los estudiantes a la qu\u00edmica de manera l\u00fadica e interactiva mediante cajas giratorias con los diferentes elementos qu\u00edmicos, su clasificaci\u00f3n, caracter\u00edsticas, uso y presencia en la tierra.<\/p>\n<p style=\"text-align: justify\">Miriam Espinosa es profesora de qu\u00edmica del Colegio Verbo Divino y seg\u00fan su opini\u00f3n, \u201cl<span style=\"line-height: 1.3em\">os estudiantes han reaccionado muy bien a la muestra, es una experiencia muy entretenida donde tienen la oportunidad de ver los elementos qu\u00edmicos de una forma cercana y comprobar adem\u00e1s lo que uno les hab\u00eda contado en clases. Es fant\u00e1stico poder contar con este tipo de itinerancias en el colegio.<\/span><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" src=\"images\/IMAGENES-RM-NORTE\/tabla%20periodica%20VD.jpg\" border=\"0\" width=\"400\" style=\"margin: 5px;border: 5px solid black;float: left\" \/><\/p>\n<p style=\"text-align: justify\">Para Diego Rodr\u00edguez, estudiante de segundo medio del mismo establecimiento, \u201cla muestra es algo que nunca antes hab\u00eda visto y me parece muy interesante, porque tiene datos e informaci\u00f3n que no habr\u00eda imaginado, como cu\u00e1nto tiene uno de cierto elemento en el cuerpo o cu\u00e1nto hay de otro en la tierra, pude ver cosas que no me imagin\u00e9 que exist\u00edan\u201d.<\/p>\n<p style=\"text-align: justify\">La exposici\u00f3n, que fue desarrollada el 2011 por el Centro Interactivo de las Ciencias, las Artes y la Tecnolog\u00eda (CICAT) y dise\u00f1ada por docentes de la Facultad de Ciencias Qu\u00edmicas de la Universidad de Concepci\u00f3n, \u00a0permanecer\u00e1 en el Colegio Verbo Divino hasta el viernes 29 de agosto para continuar su itinerancia en el Colegio Juan Luis Undurraga Aninat, de Quilicura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Tabla Peri\u00f3dica Interactiva, muestra que ha recorrido gran parte de Chile, ya se encuentra en la Regi\u00f3n Metropolitana Norte donde visitar\u00e1 diferentes establecimientos educacionales y universidades. La itinerancia, que actualmente se encuentra en el Colegio Verbo Divino de Las Condes, busca acercar a los estudiantes a la qu\u00edmica de manera l\u00fadica e interactiva mediante [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-32047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"La Tabla Peri\u00f3dica Interactiva, muestra que ha recorrido gran parte de Chile, ya se encuentra en la Regi\u00f3n Metropolitana Norte donde visitar\u00e1 diferentes establecimientos educacionales y universidades. La itinerancia, que actualmente se encuentra en el Colegio Verbo Divino de Las Condes, busca acercar a los estudiantes a la qu\u00edmica de manera l\u00fadica e interactiva mediante [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-28T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:23:41+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte\",\"datePublished\":\"2014-08-28T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:23:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\"},\"wordCount\":290,\"image\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\",\"url\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\",\"name\":\"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg\",\"datePublished\":\"2014-08-28T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:23:41+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg\",\"width\":1000,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/rmnorte\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/#website\",\"url\":\"https:\/\/explora.cl\/rmnorte\/\",\"name\":\"RM Norte\",\"description\":\"RM Norte explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/rmnorte\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/explora.cl\/rmnorte\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/","og_locale":"es_ES","og_type":"article","og_title":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte","og_description":"La Tabla Peri\u00f3dica Interactiva, muestra que ha recorrido gran parte de Chile, ya se encuentra en la Regi\u00f3n Metropolitana Norte donde visitar\u00e1 diferentes establecimientos educacionales y universidades. La itinerancia, que actualmente se encuentra en el Colegio Verbo Divino de Las Condes, busca acercar a los estudiantes a la qu\u00edmica de manera l\u00fadica e interactiva mediante [&hellip;]","og_url":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/","og_site_name":"RM Norte","article_published_time":"2014-08-28T04:00:00+00:00","article_modified_time":"2019-05-20T17:23:41+00:00","og_image":[{"width":1000,"height":675,"url":"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/"},"author":{"name":"webman","@id":"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte","datePublished":"2014-08-28T04:00:00+00:00","dateModified":"2019-05-20T17:23:41+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/"},"wordCount":290,"image":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/","url":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/","name":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte - RM Norte","isPartOf":{"@id":"https:\/\/explora.cl\/rmnorte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg","datePublished":"2014-08-28T04:00:00+00:00","dateModified":"2019-05-20T17:23:41+00:00","author":{"@id":"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#primaryimage","url":"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg","contentUrl":"https:\/\/explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/e4d5c44c5a496510a92bb496aa533f7c.jpg","width":1000,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/rmnorte\/tabla-periodica-interactiva-se-toma-colegio-verbo-divino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/rmnorte\/"},{"@type":"ListItem","position":2,"name":"Tabla Peri\u00f3dica Interactiva comienza su itinerancia en la RM Norte"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/rmnorte\/#website","url":"https:\/\/explora.cl\/rmnorte\/","name":"RM Norte","description":"RM Norte explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/rmnorte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/rmnorte\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/explora.cl\/rmnorte\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/comments?post=32047"}],"version-history":[{"count":1,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32047\/revisions"}],"predecessor-version":[{"id":38579,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32047\/revisions\/38579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/media\/33816"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/media?parent=32047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/categories?post=32047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/rmnorte\/wp-json\/wp\/v2\/tags?post=32047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}