{"id":40303,"date":"2026-07-06T12:00:06","date_gmt":"2026-07-06T16:00:06","guid":{"rendered":"https:\/\/explora.cl\/ohiggins\/?p=40303"},"modified":"2026-07-06T14:42:22","modified_gmt":"2026-07-06T18:42:22","slug":"postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026","status":"publish","type":"post","link":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/","title":{"rendered":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026!"},"content":{"rendered":"<p><span style=\"font-weight: 400\">El Proyecto Asociativo Regional (PAR) Explora O\u2019Higgins, perteneciente al Ministerio de Ciencias, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, en colaboraci\u00f3n con la Universidad de O\u2019Higgins, se complace en invitar a la comunidad educativa a ser parte de la edici\u00f3n 2026 del Congreso Regional Explora de Investigaci\u00f3n e Innovaci\u00f3n Escolar. Se realizar\u00e1 los d\u00edas jueves 27 y viernes 28 de agosto en el Campus Colchagua de la Universidad de O&#8217;Higgins, en San Fernando.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Este Congreso tiene como objetivo brindar un espacio para que las y los estudiantes de las Academias IIE presenten sus investigaciones y proyectos de innovaci\u00f3n escolar desarrollados durante el a\u00f1o. <\/b><span style=\"font-weight: 400\">En esta instancia, podr\u00e1n compartir los avances de sus proyectos, recibir retroalimentaci\u00f3n de pares, docentes, investigadoras e investigadores, y conocer las experiencias desarrolladas por otros equipos de la regi\u00f3n.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Para esta oportunidad contamos con cupos para 20 equipos, los cuales deber\u00e1n estar conformados por m\u00ednimo dos estudiantes y un docente gu\u00eda. <\/span><b>Los equipos participantes deben pertenecer exclusivamente a las Academias IIE del PAR Explora O&#8217;Higgins 2026, y el proyecto a presentar debe ser el que han desarrollado durante el presente a\u00f1o en el marco de la iniciativa.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Catalina Pinto, Directora de PAR Explora O\u2019Higgins, extendi\u00f3 su invitaci\u00f3n a todos nuestros postulantes:\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400\">\u201cLa participaci\u00f3n en estas instancias es fundamental para continuar fortaleciendo las competencias cient\u00edficas de las y los estudiantes de la regi\u00f3n. Este espacio, les permitir\u00e1 compartir con sus pares las experiencias, hallazgos y problem\u00e1ticas surgidas de sus investigaciones. Por ello, invitamos a las academias a inscribirse y ser parte de esta enriquecedora instancia\u201d.<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00bfC\u00f3mo postular?<\/b><\/p>\n<p><span style=\"font-weight: 400\">Revisa las fechas importantes a considerar para la postulaci\u00f3n:<\/span><\/p>\n<p><b>Reuni\u00f3n virtual informativa<\/b><span style=\"font-weight: 400\"> (Telem\u00e1tica v\u00eda Zoom) 9 de julio de 2026<\/span><\/p>\n<p><b>Plazo de consultas<\/b><span style=\"font-weight: 400\"> 17 de julio de 2026<\/span><\/p>\n<p><b>Cierre de postulaciones<\/b><span style=\"font-weight: 400\"> 22 de julio de 2026 23:59 hrs.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lee las las bases y completa el formulario para concretar tu postulaci\u00f3n:<\/span><\/p>\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/18JhrhAlBLVEooGngYr7PTpjtBXb1CJlD\/view?usp=sharing\"><b>Enlace a las BASES<\/b><\/a><\/p>\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfTpmxXySZ1hkxjCZMEY5B7ExMhOX56UC9STXTIyusJtu28SQ\/viewform?usp=sharing&amp;ouid=101702061501586630356\"><b>Enlace a la postulaci\u00f3n<\/b><\/a><\/p>\n<p><span style=\"font-weight: 400\">Ante consultas, les invitamos a contact\u00e1rnos a trav\u00e9s de los siguientes canales:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Correo: <\/span><a href=\"mailto:iie.explora@uoh.cl\"><span style=\"font-weight: 400\">iie.explora@uoh.cl<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">WhatsApp: +569 61081508<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-40305\" src=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-300x200.jpg 300w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-1024x683.jpg 1024w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-768x512.jpg 768w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-1536x1024.jpg 1536w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8588-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-40306\" src=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-300x200.jpg 300w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-1024x683.jpg 1024w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-768x512.jpg 768w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-1536x1024.jpg 1536w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8596-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-40307\" src=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-300x200.jpg 300w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-1024x683.jpg 1024w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-768x512.jpg 768w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-1536x1024.jpg 1536w, https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/IMG_8583-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Proyecto Asociativo Regional (PAR) Explora O\u2019Higgins, perteneciente al Ministerio de Ciencias, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, en colaboraci\u00f3n con la Universidad de O\u2019Higgins, se complace en invitar a la comunidad educativa a ser parte de la edici\u00f3n 2026 del Congreso Regional Explora de Investigaci\u00f3n e Innovaci\u00f3n Escolar. Se realizar\u00e1 los d\u00edas jueves 27 y viernes [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":40304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-40303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El Proyecto Asociativo Regional (PAR) Explora O\u2019Higgins, perteneciente al Ministerio de Ciencias, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, en colaboraci\u00f3n con la Universidad de O\u2019Higgins, se complace en invitar a la comunidad educativa a ser parte de la edici\u00f3n 2026 del Congreso Regional Explora de Investigaci\u00f3n e Innovaci\u00f3n Escolar. Se realizar\u00e1 los d\u00edas jueves 27 y viernes [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-06T16:00:06+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T18:42:22+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1298\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\"},\"author\":{\"name\":\"nsalazar\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"headline\":\"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026!\",\"datePublished\":\"2026-07-06T16:00:06+00:00\",\"dateModified\":\"2026-07-06T18:42:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\"},\"wordCount\":371,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\",\"url\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\",\"name\":\"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg\",\"datePublished\":\"2026-07-06T16:00:06+00:00\",\"dateModified\":\"2026-07-06T18:42:22+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg\",\"width\":1920,\"height\":1298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/ohiggins\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\",\"url\":\"https:\/\/explora.cl\/ohiggins\/\",\"name\":\"O&#039;Higgins\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\",\"name\":\"nsalazar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"caption\":\"nsalazar\"},\"url\":\"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins","og_description":"El Proyecto Asociativo Regional (PAR) Explora O\u2019Higgins, perteneciente al Ministerio de Ciencias, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n, en colaboraci\u00f3n con la Universidad de O\u2019Higgins, se complace en invitar a la comunidad educativa a ser parte de la edici\u00f3n 2026 del Congreso Regional Explora de Investigaci\u00f3n e Innovaci\u00f3n Escolar. Se realizar\u00e1 los d\u00edas jueves 27 y viernes [&hellip;]","og_url":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/","og_site_name":"O&#039;Higgins","article_published_time":"2026-07-06T16:00:06+00:00","article_modified_time":"2026-07-06T18:42:22+00:00","og_image":[{"width":1920,"height":1298,"url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg","type":"image\/jpeg"}],"author":"nsalazar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nsalazar","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/"},"author":{"name":"nsalazar","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"headline":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026!","datePublished":"2026-07-06T16:00:06+00:00","dateModified":"2026-07-06T18:42:22+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/"},"wordCount":371,"commentCount":0,"image":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/","url":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/","name":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026! - O&#039;Higgins","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg","datePublished":"2026-07-06T16:00:06+00:00","dateModified":"2026-07-06T18:42:22+00:00","author":{"@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"breadcrumb":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#primaryimage","url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg","contentUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2026\/07\/Web.jpg","width":1920,"height":1298},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-abiertas-al-congreso-regional-de-investigacion-e-innovacion-escolar-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/ohiggins\/"},{"@type":"ListItem","position":2,"name":"\u00a1Postulaciones abiertas al Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar 2026!"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/ohiggins\/#website","url":"https:\/\/explora.cl\/ohiggins\/","name":"O&#039;Higgins","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0","name":"nsalazar","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","caption":"nsalazar"},"url":"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/40303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/comments?post=40303"}],"version-history":[{"count":2,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/40303\/revisions"}],"predecessor-version":[{"id":40309,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/40303\/revisions\/40309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media\/40304"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media?parent=40303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/categories?post=40303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/tags?post=40303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}