{"id":39681,"date":"2024-03-11T10:02:27","date_gmt":"2024-03-11T13:02:27","guid":{"rendered":"https:\/\/explora.cl\/ohiggins\/?p=39681"},"modified":"2025-03-17T13:39:11","modified_gmt":"2025-03-17T16:39:11","slug":"postulaciones-par-explora-ohiggins-2024","status":"publish","type":"post","link":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/","title":{"rendered":"PAR Explora O\u00b4Higgins 2025-2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":23,"featured_media":39888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[136],"tags":[],"class_list":["post-39681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugar-1"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T13:02:27+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T16:39:11+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"797\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"739\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\"},\"author\":{\"name\":\"nsalazar\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"headline\":\"PAR Explora O\u00b4Higgins 2025-2026\",\"datePublished\":\"2024-03-11T13:02:27+00:00\",\"dateModified\":\"2025-03-17T16:39:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\"},\"wordCount\":5,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png\",\"articleSection\":[\"Lugar 1\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\",\"url\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\",\"name\":\"PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png\",\"datePublished\":\"2024-03-11T13:02:27+00:00\",\"dateModified\":\"2025-03-17T16:39:11+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png\",\"contentUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png\",\"width\":797,\"height\":739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/ohiggins\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAR Explora O\u00b4Higgins 2025-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\",\"url\":\"https:\/\/explora.cl\/ohiggins\/\",\"name\":\"O&#039;Higgins\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\",\"name\":\"nsalazar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"caption\":\"nsalazar\"},\"url\":\"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/","og_locale":"es_ES","og_type":"article","og_title":"PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins","og_url":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/","og_site_name":"O&#039;Higgins","article_published_time":"2024-03-11T13:02:27+00:00","article_modified_time":"2025-03-17T16:39:11+00:00","og_image":[{"width":797,"height":739,"url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png","type":"image\/png"}],"author":"nsalazar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nsalazar","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/"},"author":{"name":"nsalazar","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"headline":"PAR Explora O\u00b4Higgins 2025-2026","datePublished":"2024-03-11T13:02:27+00:00","dateModified":"2025-03-17T16:39:11+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/"},"wordCount":5,"commentCount":0,"image":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png","articleSection":["Lugar 1"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/","url":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/","name":"PAR Explora O\u00b4Higgins 2025-2026 - O&#039;Higgins","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png","datePublished":"2024-03-11T13:02:27+00:00","dateModified":"2025-03-17T16:39:11+00:00","author":{"@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"breadcrumb":{"@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#primaryimage","url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png","contentUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2024\/03\/icono-PAR-Explora-O\u00b4Higgins.png","width":797,"height":739},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/ohiggins\/postulaciones-par-explora-ohiggins-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/ohiggins\/"},{"@type":"ListItem","position":2,"name":"PAR Explora O\u00b4Higgins 2025-2026"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/ohiggins\/#website","url":"https:\/\/explora.cl\/ohiggins\/","name":"O&#039;Higgins","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0","name":"nsalazar","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","caption":"nsalazar"},"url":"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/39681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/comments?post=39681"}],"version-history":[{"count":6,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/39681\/revisions"}],"predecessor-version":[{"id":39889,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/39681\/revisions\/39889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media\/39888"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media?parent=39681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/categories?post=39681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/tags?post=39681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}