{"id":38241,"date":"2019-08-21T17:14:02","date_gmt":"2019-08-21T21:14:02","guid":{"rendered":"https:\/\/explora.cl\/ohiggins\/?p=38241"},"modified":"2019-12-05T10:13:29","modified_gmt":"2019-12-05T13:13:29","slug":"ciencia_genero_educacion","status":"publish","type":"post","link":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/","title":{"rendered":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n"},"content":{"rendered":"<p>Finalizaremos estas jornada 2019 con el Seminario &#8220;Ciencia, g\u00e9nero y educaci\u00f3n&#8221;, que se realizar\u00e1 en dependencias de la UOH, Campus Rancagua el 19 de diciembre desde las 9:00 horas con un programa de actividades durante todo el d\u00eda<\/p>\n<p>9:00 Saludos autoridades<\/p>\n<p>9:30 Panel de conversaci\u00f3n &#8220;Ciencia, g\u00e9nero y educaci\u00f3n: \u00bfque acciones deber\u00edamos implementar para la uni\u00f3n de estos tres conceptos?<\/p>\n<p>10:45 Coffe<\/p>\n<p>11:15 Exposici\u00f3n de talleres anuales<\/p>\n<p>12:00 Charla Mar\u00eda Teresa Ruiz<\/p>\n<p>13:30 cierre jornada de ma\u00f1ana<\/p>\n<p>15:00 Desaf\u00edo de rob\u00f3tica: grupos conformados por mujeres<\/p>\n<p><strong>Un aporte a la disminuci\u00f3n de la brecha de g\u00e9nero en carreras STEM<\/strong><\/p>\n<p>Los datos se\u00f1alan que solo el 28% de los\/as investigadores\/as del mundo son mujeres, las que adem\u00e1s, seg\u00fan datos de UNESCO est\u00e1n sub representadas en \u00e1reas como ingenier\u00eda, f\u00edsica y matem\u00e1ticas, teniendo Chile bajos porcentajes de graduadas en ciencias e ingenier\u00eda, reflejando un porcentaje menor al 35% en ambas carreras. Frente a lo anterior es que diversas instituciones a nivel pa\u00eds, han puesto \u00e9nfasis para colaborar con el aumento de la participaci\u00f3n de la mujer en \u00e1reas STEM (Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). A modo de referencia cabe mencionar que este a\u00f1o se lanz\u00f3 en Chile el Proyecto UNESCO: SAGA, el que se ejecutar\u00e1 en el pa\u00eds con el apoyo de diversos organismos entre ellos el Ministerio de Ciencia y Tecnolog\u00eda; el Ministerio de la Mujer y CONICYT.<\/p>\n<p>La Universidad de O\u2019Higgins no est\u00e1 ajena a esta realidad y es por ello que a trav\u00e9s del PAR Explora de la regi\u00f3n se encuentra organizando la actividad \u201cCiencia, g\u00e9nero y educaci\u00f3n\u201d,\u00a0 la que tiene por objetivo visibilizar el aporte de la mujer en el desarrollo de la ciencia, la tecnolog\u00eda y la innovaci\u00f3n, y al mismo tiempo, presentar acciones, metodolog\u00edas educativas y maneras de hacer ciencia que pueden generar acercamientos tempranos libres del sesgo de g\u00e9nero, contribuyendo as\u00ed al aumento de la participaci\u00f3n de ni\u00f1as, j\u00f3venes y mujeres en acciones asociadas a las \u00e1reas STEM.<\/p>\n<p>La actividad contempla dos etapas: una primera etapa de talleres para profesores\/as y conversatorios para la comunidad general, en \u00e9stos se trabajan tem\u00e1ticas asociadas a g\u00e9nero y ciencia y se entregan herramientas para el trabajo curricular y extra curricular con la ni\u00f1ez y la juventud en los centros educativos. La segunda etapa en tanto, tiene que ver con la actividad c\u00falmine donde se reunir\u00e1n los trabajos realizados por los diversos grupos quienes, expondr\u00e1n sus experiencias a la comunidad el 26 de noviembre en dependencias de la Universidad de O\u2019Higgins, donde, adem\u00e1s podr\u00e1n compartir con expositoras como la astr\u00f3noma, Premio Nacional de Ciencias, Mar\u00eda Teresa Ruiz, quien fue Presidenta de la Academia de Ciencias \u00a0y actualmente Directora de Comunidad Mujer.<\/p>\n<p><strong>Talleres curriculares<\/strong><\/p>\n<p><strong>\u00a0<\/strong>En el marco de esta actividad, la Oficina de Equidad y G\u00e9nero de la Universidad de O\u2019Higgins, junto a PAR Explora O\u2019Higgins, se encuentran realizando los talleres \u201cciencia, g\u00e9nero y curr\u00edculo\u201d donde se discute sobre c\u00f3mo insertar tem\u00e1ticas de g\u00e9nero y ciencia en el curr\u00edculo para estudiantes de todos los niveles y diversas \u00e1reas.<\/p>\n<p>Claudia Alarc\u00f3n de la Oficina de Equidad y G\u00e9nero nos explica que \u201ces un aporte entregar herramientas pr\u00e1cticas al docente para poder trabajar las relaciones y la tem\u00e1tica de g\u00e9nero en el curr\u00edculo. En este sentido, esperamos poder ir trabajando sobre todo desde educaci\u00f3n primaria, ya que todos los estudios se\u00f1alan que la educaci\u00f3n primaria es el ciclo m\u00e1s abandonado en el trabajo en ciencias, g\u00e9nero y educaci\u00f3n\u201d<\/p>\n<p>La experta en la tem\u00e1tica de g\u00e9nero se\u00f1ala que \u201csomos una de las regiones con menos mujeres estudiando en carreras tradicionalmente masculinizadas. En nuestra universidad (UOH) tenemos 82 mujeres en la Escuela de Ingenier\u00eda, de un Universo de 389 estudiantes. A esto se suma que somos una de las regiones con mayores \u00edndices de violencia de g\u00e9nero, lo que sin lugar a dudas nos preocupa y pensamos como universidad, que debemos aportar a cambiar esta realidad\u201d.<\/p>\n<p><strong>Talleres <\/strong><strong>de Rob\u00f3tica<\/strong><\/p>\n<p>Frente a lo anterior es que tambi\u00e9n se han implementado un taller STEM y un taller de rob\u00f3tica, el primero dirigido a estudiantes de ense\u00f1anza media y el segundo a profesores\/as que posean grupos de estudiantes conformados al menos por un 50% de estudiantes mujeres. \u201cHemos decidido implementar estos talleres de rob\u00f3tica, en particular entre ni\u00f1as y profesoras, ya que queremos generar acercamientos tempranos a estas tecnolog\u00edas y as\u00ed contribuir a disminuir los sesgos de g\u00e9nero. Esto lo realizaremos primero mediante una capacitaci\u00f3n a docentes de la regi\u00f3n, y posterior a eso seguiremos trabajando con los profesores\/as y sus estudiantes, momento en el que contaremos con el apoyo de estudiantes, docentes y acad\u00e9micos de la Escuela de Ingenier\u00eda de la UOH, con quienes haremos tutor\u00edas que consisten en acompa\u00f1ar a estos grupos en sus actividades iniciales y encaminarlos para que participen en desaf\u00edos de rob\u00f3tica, programaci\u00f3n u otras acciones y posteriormente expongan sus experiencias en el seminario del pr\u00f3ximo 26 de noviembre&#8221;, se\u00f1ala Rodrigo Verschae, Director del PAR Explora O\u2019Higgins y acad\u00e9mico del Instituto de Ingenier\u00eda de la UOH.<\/p>\n<p>Al cierre de esta nota ya se han realizado 4 talleres en la regi\u00f3n, llegando a m\u00e1s de 50 profesores\/as de distintas comunas. Desde septiembre se inicia el trabajo con grupos de estudiantes; tambi\u00e9n comenzar\u00e1n los talleres de rob\u00f3tica, cuya capacitaci\u00f3n docente ser\u00e1 el d\u00eda 1 de octubre en el Campus Rancagua de la Universidad de O\u2019Higgins. <a href=\"https:\/\/forms.gle\/HHo2Gh3XXs4WDxrK9\">Inscripciones ac\u00e1<\/a> (pinchar)<\/p>\n<p>Las inscripciones para el Seminario del 26 de noviembre se encontrar\u00e1n disponibles desde el mes de octubre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalizaremos estas jornada 2019 con el Seminario &#8220;Ciencia, g\u00e9nero y educaci\u00f3n&#8221;, que se realizar\u00e1 en dependencias de la UOH, Campus Rancagua el 19 de diciembre desde las 9:00 horas con un programa de actividades durante todo el d\u00eda<\/p>\n","protected":false},"author":23,"featured_media":38243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[151,136],"tags":[19,148,21],"class_list":["post-38241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banner","category-lugar-1","tag-1000-cientificos-1000-aulas","tag-charlas-cientificas","tag-explora-conicyt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Finalizaremos estas jornada 2019 con el Seminario &quot;Ciencia, g\u00e9nero y educaci\u00f3n&quot;, que se realizar\u00e1 en dependencias de la UOH, Campus Rancagua el 19 de diciembre desde las 9:00 horas con un programa de actividades durante todo el d\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"O&#039;Higgins\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-21T21:14:02+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-05T13:13:29+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"nsalazar\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\"},\"author\":{\"name\":\"nsalazar\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"headline\":\"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n\",\"datePublished\":\"2019-08-21T21:14:02+00:00\",\"dateModified\":\"2019-12-05T13:13:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\"},\"wordCount\":1007,\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png\",\"keywords\":[\"1000 cient\u00edficos 1000 aulas\",\"charlas cient\u00edficas\",\"Explora Conicyt\"],\"articleSection\":[\"Banner\",\"Lugar 1\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\",\"url\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\",\"name\":\"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png\",\"datePublished\":\"2019-08-21T21:14:02+00:00\",\"dateModified\":\"2019-12-05T13:13:29+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png\",\"contentUrl\":\"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png\",\"width\":736,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/ohiggins\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#website\",\"url\":\"https:\/\/explora.cl\/ohiggins\/\",\"name\":\"O&#039;Higgins\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0\",\"name\":\"nsalazar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g\",\"caption\":\"nsalazar\"},\"url\":\"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/","og_locale":"es_ES","og_type":"article","og_title":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins","og_description":"Finalizaremos estas jornada 2019 con el Seminario \"Ciencia, g\u00e9nero y educaci\u00f3n\", que se realizar\u00e1 en dependencias de la UOH, Campus Rancagua el 19 de diciembre desde las 9:00 horas con un programa de actividades durante todo el d\u00eda","og_url":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/","og_site_name":"O&#039;Higgins","article_published_time":"2019-08-21T21:14:02+00:00","article_modified_time":"2019-12-05T13:13:29+00:00","og_image":[{"width":736,"height":420,"url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png","type":"image\/png"}],"author":"nsalazar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nsalazar","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/"},"author":{"name":"nsalazar","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"headline":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n","datePublished":"2019-08-21T21:14:02+00:00","dateModified":"2019-12-05T13:13:29+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/"},"wordCount":1007,"image":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png","keywords":["1000 cient\u00edficos 1000 aulas","charlas cient\u00edficas","Explora Conicyt"],"articleSection":["Banner","Lugar 1"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/","url":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/","name":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n - O&#039;Higgins","isPartOf":{"@id":"https:\/\/explora.cl\/ohiggins\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png","datePublished":"2019-08-21T21:14:02+00:00","dateModified":"2019-12-05T13:13:29+00:00","author":{"@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0"},"breadcrumb":{"@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#primaryimage","url":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png","contentUrl":"https:\/\/explora.cl\/ohiggins\/wp-content\/uploads\/sites\/8\/2019\/08\/CIENCIA-G\u00c9NERO-Y-EDUCACI\u00d3N-PAREXPLORA-BANNER-2.png","width":736,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/ohiggins\/ciencia_genero_educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/ohiggins\/"},{"@type":"ListItem","position":2,"name":"Participa de nuestras acciones en Ciencia, g\u00e9nero y educaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/ohiggins\/#website","url":"https:\/\/explora.cl\/ohiggins\/","name":"O&#039;Higgins","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/ohiggins\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/3240d62ad2624da9148a475abbc509b0","name":"nsalazar","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/ohiggins\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8cf276f31998a0865a3b90e4d663d91b97848887282c9f9a56cad57ff01cc7e?s=96&d=mm&r=g","caption":"nsalazar"},"url":"https:\/\/explora.cl\/ohiggins\/author\/nsalazar\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/38241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/comments?post=38241"}],"version-history":[{"count":10,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/38241\/revisions"}],"predecessor-version":[{"id":38320,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/posts\/38241\/revisions\/38320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media\/38243"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/media?parent=38241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/categories?post=38241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/ohiggins\/wp-json\/wp\/v2\/tags?post=38241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}