{"id":38856,"date":"2020-08-04T12:01:25","date_gmt":"2020-08-04T16:01:25","guid":{"rendered":"https:\/\/explora.cl\/atacama\/?p=38856"},"modified":"2020-08-05T10:59:14","modified_gmt":"2020-08-05T14:59:14","slug":"basespipe-2","status":"publish","type":"post","link":"https:\/\/explora.cl\/atacama\/basespipe-2\/","title":{"rendered":"Cierre de postulaciones: todo un \u00e9xito de convocatoria"},"content":{"rendered":"<p><span style=\"color: #008000\"><strong>Queremos agradecer a todas y todos quienes se sumaron a esta convocatoria. Actualmente estamos en proceso de evaluaci\u00f3n de las postulaciones, las cuales daremos a conocer en los pr\u00f3ximos d\u00edas. \u00a0Est\u00e9n al pendiente de sus correos electr\u00f3nicos, ya que les informaremos por esa v\u00eda y por nuestras redes sociales el viernes 7 de agosto.\u00a0<\/strong><\/span><\/p>\n<p>El \u201cPrograma de Indagaci\u00f3n para Primeras Edades (PIPE)\u201d busca fortalecer las competencias cient\u00edficas de los equipos pedag\u00f3gicos de educaci\u00f3n parvularia y desarrollar en ni\u00f1os y ni\u00f1as las competencias necesarias para que conozcan y comprendan el mundo que los rodea.<\/p>\n<p>Para esto se han dise\u00f1ado dos m\u00f3dulos independientes, pero complementarios, uno centrado en \u201cPlantas\u201d y otro en \u201cAnimales\u201d. Este programa ya tuvo una primera experiencia durante el 2019 en la Regi\u00f3n de Atacama.<\/p>\n<p><strong>Dudas y consultas: katia.riveros@uda.cl<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queremos agradecer a todas y todos quienes se sumaron a esta convocatoria. Actualmente estamos en proceso de evaluaci\u00f3n de las postulaciones, las cuales daremos a conocer en los pr\u00f3ximos d\u00edas. \u00a0Est\u00e9n al pendiente de sus correos electr\u00f3nicos, ya que les informaremos por esa v\u00eda y por nuestras redes sociales el viernes 7 de agosto.\u00a0<\/p>\n","protected":false},"author":20,"featured_media":38808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[137,1],"tags":[],"class_list":["post-38856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugar-2","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/atacama\/basespipe-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Queremos agradecer a todas y todos quienes se sumaron a esta convocatoria. Actualmente estamos en proceso de evaluaci\u00f3n de las postulaciones, las cuales daremos a conocer en los pr\u00f3ximos d\u00edas. \u00a0Est\u00e9n al pendiente de sus correos electr\u00f3nicos, ya que les informaremos por esa v\u00eda y por nuestras redes sociales el viernes 7 de agosto.\u00a0\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/atacama\/basespipe-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Atacama\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T16:01:25+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-05T14:59:14+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"737\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"ExploraAtacama\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"ExploraAtacama\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/\"},\"author\":{\"name\":\"ExploraAtacama\",\"@id\":\"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3\"},\"headline\":\"Cierre de postulaciones: todo un \u00e9xito de convocatoria\",\"datePublished\":\"2020-08-04T16:01:25+00:00\",\"dateModified\":\"2020-08-05T14:59:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/\"},\"wordCount\":154,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png\",\"articleSection\":[\"Lugar 2\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/explora.cl\/atacama\/basespipe-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/\",\"url\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/\",\"name\":\"Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/atacama\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png\",\"datePublished\":\"2020-08-04T16:01:25+00:00\",\"dateModified\":\"2020-08-05T14:59:14+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/atacama\/basespipe-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png\",\"contentUrl\":\"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png\",\"width\":737,\"height\":421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/atacama\/basespipe-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/atacama\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cierre de postulaciones: todo un \u00e9xito de convocatoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/atacama\/#website\",\"url\":\"https:\/\/explora.cl\/atacama\/\",\"name\":\"Atacama\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/atacama\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3\",\"name\":\"ExploraAtacama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/atacama\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e2fd819b7985a746e8ea39b36909cf1a17dc034046e230e83eb1534d0a52b24?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e2fd819b7985a746e8ea39b36909cf1a17dc034046e230e83eb1534d0a52b24?s=96&d=mm&r=g\",\"caption\":\"ExploraAtacama\"},\"url\":\"https:\/\/explora.cl\/atacama\/author\/dortiz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/atacama\/basespipe-2\/","og_locale":"es_ES","og_type":"article","og_title":"Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama","og_description":"Queremos agradecer a todas y todos quienes se sumaron a esta convocatoria. Actualmente estamos en proceso de evaluaci\u00f3n de las postulaciones, las cuales daremos a conocer en los pr\u00f3ximos d\u00edas. \u00a0Est\u00e9n al pendiente de sus correos electr\u00f3nicos, ya que les informaremos por esa v\u00eda y por nuestras redes sociales el viernes 7 de agosto.\u00a0","og_url":"https:\/\/explora.cl\/atacama\/basespipe-2\/","og_site_name":"Atacama","article_published_time":"2020-08-04T16:01:25+00:00","article_modified_time":"2020-08-05T14:59:14+00:00","og_image":[{"width":737,"height":421,"url":"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png","type":"image\/png"}],"author":"ExploraAtacama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ExploraAtacama","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/"},"author":{"name":"ExploraAtacama","@id":"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3"},"headline":"Cierre de postulaciones: todo un \u00e9xito de convocatoria","datePublished":"2020-08-04T16:01:25+00:00","dateModified":"2020-08-05T14:59:14+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/"},"wordCount":154,"commentCount":0,"image":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png","articleSection":["Lugar 2"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explora.cl\/atacama\/basespipe-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/","url":"https:\/\/explora.cl\/atacama\/basespipe-2\/","name":"Cierre de postulaciones: todo un \u00e9xito de convocatoria - Atacama","isPartOf":{"@id":"https:\/\/explora.cl\/atacama\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png","datePublished":"2020-08-04T16:01:25+00:00","dateModified":"2020-08-05T14:59:14+00:00","author":{"@id":"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3"},"breadcrumb":{"@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/atacama\/basespipe-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#primaryimage","url":"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png","contentUrl":"https:\/\/explora.cl\/atacama\/wp-content\/uploads\/sites\/5\/2020\/07\/BANNER.png","width":737,"height":421},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/atacama\/basespipe-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/atacama\/"},{"@type":"ListItem","position":2,"name":"Cierre de postulaciones: todo un \u00e9xito de convocatoria"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/atacama\/#website","url":"https:\/\/explora.cl\/atacama\/","name":"Atacama","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/atacama\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/atacama\/#\/schema\/person\/1e89437dfd0db398617a5057c75b8bf3","name":"ExploraAtacama","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/atacama\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2e2fd819b7985a746e8ea39b36909cf1a17dc034046e230e83eb1534d0a52b24?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e2fd819b7985a746e8ea39b36909cf1a17dc034046e230e83eb1534d0a52b24?s=96&d=mm&r=g","caption":"ExploraAtacama"},"url":"https:\/\/explora.cl\/atacama\/author\/dortiz\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/posts\/38856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/comments?post=38856"}],"version-history":[{"count":3,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/posts\/38856\/revisions"}],"predecessor-version":[{"id":38859,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/posts\/38856\/revisions\/38859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/media\/38808"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/media?parent=38856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/categories?post=38856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/atacama\/wp-json\/wp\/v2\/tags?post=38856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}