{"id":37745,"date":"2014-06-25T00:00:00","date_gmt":"2014-06-25T04:00:00","guid":{"rendered":"https:\/\/explora.cl\/araucania\/blog\/2014\/06\/25\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014\/"},"modified":"2019-05-20T19:11:43","modified_gmt":"2019-05-20T19:11:43","slug":"en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3","status":"publish","type":"post","link":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/","title":{"rendered":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3434\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/06\/1d74984588d9effd2a11e9255005a86c.jpg\" alt=\"\" width=\"1000\" height=\"711\" \/><\/p>\n<p><em><strong>Ocho establecimientos de La Araucan\u00eda recibir\u00e1n la visita de la Ciencia Itinerante este 2014. La Escuela Lidia Gonz\u00e1lez de Collipulli es el pr\u00f3ximo destino de esta aventura cient\u00edfica.<\/strong><\/em><\/p>\n<p>La Ciencia Itinerante, una de las actividades m\u00e1s emblem\u00e1ticas del Proyecto EXPLORA CONICYT Regi\u00f3n de La Araucan\u00eda, inici\u00f3 oficialmente su recorrido 2014, el que incluir\u00e1 ocho establecimientos de distintas comunas de nuestra zona y beneficiar\u00e1 a m\u00e1s de tres mil ni\u00f1os y ni\u00f1as.<\/p>\n<p>El evento de lanzamiento se realiz\u00f3 en el Colegio Santa Cruz, donde alrededor de 400 estudiantes de primer a octavo a\u00f1o b\u00e1sico aprendieron distintos fen\u00f3menos f\u00edsicos y qu\u00edmicos a trav\u00e9s de sorprendentes experiencias interactivas, que buscan estimular el inter\u00e9s por la ciencia y tecnolog\u00eda en ni\u00f1os, ni\u00f1as y j\u00f3venes de La Araucan\u00eda.<\/p>\n<p>M\u00f3dulos de \u00f3ptica y luz, percepci\u00f3n, electricidad y magnetismo, qu\u00edmica y estados de la materia se instalaron en la biblioteca del establecimiento, en los cuales escolares manipularon instrumentos, observaron directamente cambios nunca antes vistos, como la sublimaci\u00f3n, y sintieron en sus cuerpos efectos de fen\u00f3menos como la electricidad, lo que les permiti\u00f3 tener un encuentro cercano y divertido con la ciencia.<\/p>\n<p><img decoding=\"async\" class=\" alignleft size-full wp-image-3435\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/06\/Ciencia-Itinerante-Colegio-Santa-Cruz-2014-1.jpg\" border=\"0\" alt=\"\" align=\"left\" width=\"366\" height=\"260\" \/>Un grupo de monitores, compuesto por j\u00f3venes estudiantes de la Universidad de La Frontera, fue el encargado de llevar a cabo los asombrosos experimentos y explicar los conceptos asociados a cada una las demostraciones, lo que propici\u00f3 un aprendizaje significativo en los alumnos y alumnas.<\/p>\n<p><strong>Ciencia Itinerante 2014<\/strong><\/p>\n<p><span style=\"line-height: 1.3em\">La Ciencia Itinerante es una actividad que busca cautivar a estudiantes de educaci\u00f3n b\u00e1sica con el mundo cient\u00edfico, mostr\u00e1ndoles que, m\u00e1s all\u00e1 de los contenidos te\u00f3ricos, la ciencia es un \u00e1mbito fascinante lleno de aspectos por descubrir y explorar.\u00a0<\/span><\/p>\n<p>Este 2014, la aventura cient\u00edfica incluir\u00e1 ocho establecimientos de la regi\u00f3n, a trav\u00e9s de los cuales se espera llegar a m\u00e1s de tres mil estudiantes. Algunos de ellos son la Escuela General Prieto, Escuela Lidia Gonz\u00e1lez de Collipulli, Escuela Los Nogales de Renaico, Escuela Emprender de Temuco y Escuela Metrenco de Padre Las Casas, los que recibir\u00e1n la visita de la Ciencia Itinerante en el primer semestre.<\/p>\n<p><strong>Los ni\u00f1os cuentan su experiencia<\/strong><\/p>\n<p><img decoding=\"async\" class=\" alignleft size-full wp-image-3436\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/06\/Ciencia-Itinerante-Colegio-Santa-Cruz-2014-cua-1.jpg\" border=\"0\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cLo que m\u00e1s me gust\u00f3 fue lo de los imanes, porque aprend\u00ed que cuando son signos diferentes se pueden pegar, pero cuando son iguales no pueden. Tambi\u00e9n me gust\u00f3 ver los l\u00edquidos, los s\u00f3lidos y el gas. La actividad fue muy divertida y aprend\u00ed harto\u201d.<\/p>\n<p>Paula Zurita, estudiante de segundo b\u00e1sico.<\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-3437\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/06\/Ciencia-Itinerante-Colegio-Santa-Cruz-2014-cua-2.jpg\" border=\"0\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cTodo me pareci\u00f3 s\u00faper entretenido, porque me gusta lo relacionado con la ciencia. El m\u00f3dulo de la electricidad fue el que m\u00e1s me gust\u00f3, porque al tocar la esfera y tocar despu\u00e9s a otras personas uno sent\u00eda que pasaba la electricidad, y aprend\u00ed que eso ocurre porque somos conductores de la electricidad\u201d.<\/p>\n<p>Jos\u00e9 Tom\u00e1s Baeza, alumno de cuarto b\u00e1sico.<\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-3438\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/06\/Ciencia-Itinerante-Colegio-Santa-Cruz-2014-cua-3.jpg\" border=\"0\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>&#8220;Yo visit\u00e9 todos los m\u00f3dulos y fue muy divertido, porque siempre me ha gustado mucho la ciencia. Lo que m\u00e1s me llam\u00f3 la atenci\u00f3n fue el m\u00f3dulo donde estaban los estados de la materia y lo de la sublimaci\u00f3n&#8221;.<\/p>\n<p>B\u00e1rbara Bol\u00edvar, alumna de cuarto b\u00e1sico.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1494635950754452.1073741961.1388936647991050&amp;type=3&amp;uploaded=35\" target=\"_blank\" rel=\"noopener noreferrer\">Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes<\/a><\/p>\n<p style=\"text-align: justify\">Periodista: Carolina Nahuelpi \u00c1lvarez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocho establecimientos de La Araucan\u00eda recibir\u00e1n la visita de la Ciencia Itinerante este 2014. La Escuela Lidia Gonz\u00e1lez de Collipulli es el pr\u00f3ximo destino de esta aventura cient\u00edfica. La Ciencia Itinerante, una de las actividades m\u00e1s emblem\u00e1ticas del Proyecto EXPLORA CONICYT Regi\u00f3n de La Araucan\u00eda, inici\u00f3 oficialmente su recorrido 2014, el que incluir\u00e1 ocho establecimientos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-37745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Ocho establecimientos de La Araucan\u00eda recibir\u00e1n la visita de la Ciencia Itinerante este 2014. La Escuela Lidia Gonz\u00e1lez de Collipulli es el pr\u00f3ximo destino de esta aventura cient\u00edfica. La Ciencia Itinerante, una de las actividades m\u00e1s emblem\u00e1ticas del Proyecto EXPLORA CONICYT Regi\u00f3n de La Araucan\u00eda, inici\u00f3 oficialmente su recorrido 2014, el que incluir\u00e1 ocho establecimientos [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-25T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:11:43+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014\",\"datePublished\":\"2014-06-25T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:11:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\"},\"wordCount\":582,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\",\"url\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\",\"name\":\"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg\",\"datePublished\":\"2014-06-25T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:11:43+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg\",\"width\":1000,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/araucania\/#website\",\"url\":\"https:\/\/explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/","og_locale":"es_ES","og_type":"article","og_title":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda","og_description":"Ocho establecimientos de La Araucan\u00eda recibir\u00e1n la visita de la Ciencia Itinerante este 2014. La Escuela Lidia Gonz\u00e1lez de Collipulli es el pr\u00f3ximo destino de esta aventura cient\u00edfica. La Ciencia Itinerante, una de las actividades m\u00e1s emblem\u00e1ticas del Proyecto EXPLORA CONICYT Regi\u00f3n de La Araucan\u00eda, inici\u00f3 oficialmente su recorrido 2014, el que incluir\u00e1 ocho establecimientos [&hellip;]","og_url":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/","og_site_name":"Araucan\u00eda","article_published_time":"2014-06-25T04:00:00+00:00","article_modified_time":"2019-05-20T19:11:43+00:00","og_image":[{"width":1000,"height":711,"url":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/"},"author":{"name":"webman","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014","datePublished":"2014-06-25T04:00:00+00:00","dateModified":"2019-05-20T19:11:43+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/"},"wordCount":582,"commentCount":0,"image":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/","url":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/","name":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014 - Araucan\u00eda","isPartOf":{"@id":"https:\/\/explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg","datePublished":"2014-06-25T04:00:00+00:00","dateModified":"2019-05-20T19:11:43+00:00","author":{"@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#primaryimage","url":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg","contentUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1d74984588d9effd2a11e9255005a86c.jpg","width":1000,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/araucania\/en-el-colegio-santa-cruz-se-lanza-oficialmente-la-ciencia-itinerante-2014-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"En el Colegio Santa Cruz se lanza oficialmente la Ciencia Itinerante 2014"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/araucania\/#website","url":"https:\/\/explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/37745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=37745"}],"version-history":[{"count":1,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/37745\/revisions"}],"predecessor-version":[{"id":38545,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/37745\/revisions\/38545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/media\/141"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=37745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=37745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=37745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}