{"id":2430,"date":"2017-09-28T00:00:00","date_gmt":"2017-09-28T04:00:00","guid":{"rendered":"https:\/\/explora.cl\/araucania\/blog\/2017\/09\/28\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/"},"modified":"2019-05-20T18:51:25","modified_gmt":"2019-05-20T18:51:25","slug":"a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania","status":"publish","type":"post","link":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/","title":{"rendered":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-27963\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/09\/araucania2.JPG\" alt=\"araucania2\" style=\"margin-left: auto;margin-right: auto\" width=\"500\" height=\"333\" \/><\/p>\n<p style=\"text-align: justify\"><em>Son m\u00e1s de un centenar de estudiantes de La Araucan\u00eda, quienes&nbsp; ya han tenido la posibilidad de participar del entretenido y din\u00e1mico taller: <strong>\u201cAraucan\u00eda ilustrada, una loca geograf\u00eda\u201d<\/strong>, organizado por el PAR Explora de CONICYT LA Araucan\u00eda, ejecutado por la Universidad de La Frontera y el Museo Regional de La Araucan\u00eda.<\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\">La actividad est\u00e1 dirigida a estudiantes de educaci\u00f3n b\u00e1sica y tiene por objetivo que los escolares reconozcan caracter\u00edsticas geogr\u00e1ficas, hist\u00f3ricas e identitarias de cada comuna de la regi\u00f3n, a trav\u00e9s de ilustraciones que sintetizan elementos procedentes desde la toponimia del lugar, es decir, desde el origen del nombre de cada una de las 32 comunas que conforman nuestra regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">El taller invita a los ni\u00f1os y ni\u00f1as a que identifiquen los principales componentes culturales y geogr\u00e1ficos de cada comuna, a trav\u00e9s de lo que se expresa en las 32 im\u00e1genes ilustradas de las comunas que conforman la exposici\u00f3n temporal del Museo <strong>\u201cAraucan\u00eda en Palabras: un nombre, un lugar, una historia\u201d<\/strong>.<\/p>\n<p style=\"text-align: justify\">Durante la jornada, los estudiantes tambi\u00e9n deben armar un puzle de goma gigante de La Araucan\u00eda en el cual sit\u00faan cada una de las comunas que lo componen, posteriormente dibujan un nuevo afiche que identifique seg\u00fan ellos de mejor manera la comuna de donde ellos provienen.<\/p>\n<p style=\"text-align: justify\">El taller finaliza con un recorrido guiado por la exhibici\u00f3n permanente con que cuenta el Museo Regional; en ella se exhiben alrededor de 500 objetos pertenecientes a la colecci\u00f3n patrimonial del Museo, que en su conjunto dan cuenta del desarrollo cultural de la regi\u00f3n desde tiempos prehisp\u00e1nicos hasta momentos hist\u00f3ricos.<\/p>\n<p style=\"text-align: justify\">Cabe destacar que la exposici\u00f3n <strong>\u201cAraucan\u00eda en palabras: un nombre, un lugar, una historia\u201d<\/strong>, estar\u00e1 abierta al p\u00fablico en dependencias del sal\u00f3n de exposiciones temporales del Museo Regional de La Araucan\u00eda hasta finales del mes de octubre.<\/p>\n<p style=\"text-align: justify\">Esta actividad se enmarca dentro del convenio de colaboraci\u00f3n existente entre el PAR Explora de CONICYT La Araucan\u00eda y el Museo Regional de La Araucan\u00eda, gracias al cual se han efectuado diversos talleres durante todo este 2017, con el objetivo de favorecer el rescate y valoraci\u00f3n de los distintos legados hist\u00f3ricos de nuestra regi\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-27964\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/09\/araucan%C3%ADa3.jpg\" alt=\"araucan\u00eda3\" width=\"1045\" height=\"280\" \/><\/p>\n<p style=\"text-align: justify\"><strong>Impresiones: <\/strong><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\" alignleft size-full wp-image-27965\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/09\/araucan%C3%ADa4.jpg\" alt=\"araucan\u00eda4\" style=\"float: left\" width=\"120\" height=\"120\" \/>\u201cMe gust\u00f3 mucho todo lo que aprend\u00ed porque me ense\u00f1aron como puedo especificar las caracter\u00edsticas de mi comuna, adem\u00e1s de interpretarlas en un dibujo.&nbsp; Tambi\u00e9n conoc\u00ed muchas cosas bonitas, cosas que no sab\u00eda, estoy muy contento de haber participado de esta actividad y gracias por la oportunidad\u201d.&nbsp;<\/p>\n<p style=\"text-align: justify\"><strong>Mauro Pav\u00e9s,&nbsp; estudiante quinto b\u00e1sico, Escuela Gabriela Mistral, Nueva Imperial.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27966\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/09\/araucan%C3%ADa5.jpg\" alt=\"araucan\u00eda5\" style=\"float: left\" width=\"120\" height=\"120\" \/>\u201cEste taller me gust\u00f3 mucho porque conoc\u00ed m\u00e1s sobre mi pueblo y la regi\u00f3n en general, tambi\u00e9n pude participar de todas las actividades que me parecieron muy divertidas y fue genial conocer un museo donde hay cosas que tan antiguas\u201d.<\/p>\n<p style=\"text-align: justify\"><strong>Martina Cifuentes, estudiante s\u00e9ptimo b\u00e1sico, Escuela Gabriela Mistral, Galvarino.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27967\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/09\/araucan%C3%ADa6.jpg\" alt=\"araucan\u00eda6\" style=\"float: left\" width=\"120\" height=\"120\" \/>\u201cLa actividad fue muy entretenida ya que conoc\u00ed m\u00e1s sobre las comunas de La Araucan\u00eda y sobre mi pueblo. Nosotros en la escuela estamos trabajando sobre la historia de Galvarino (el pueblo), as\u00ed que este taller nos sirvi\u00f3 mucho, as\u00ed que nos vamos muy agradecidos\u201d.<\/p>\n<p style=\"text-align: justify\"><strong>Pablo Rojas, estudiante s\u00e9ptimo b\u00e1sico, Escuela Gabriela Mistral, Galvarino.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.facebook.com\/pg\/explora.araucania\/photos\/?tab=album&amp;album_id=1951281635089879\"><strong>\u00a1Haz <\/strong><strong>click<\/strong><strong> aqu\u00ed&nbsp;<\/strong><strong>para<\/strong><strong> ver <\/strong><strong>la<\/strong><strong> galer\u00eda&nbsp;<\/strong><strong>de <\/strong><strong>im\u00e1genes!<\/strong><\/a><\/p>\n<p style=\"text-align: justify\"><strong>Periodista: Natalia Riquelme Espinoza. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son m\u00e1s de un centenar de estudiantes de La Araucan\u00eda, quienes&nbsp; ya han tenido la posibilidad de participar del entretenido y din\u00e1mico taller: \u201cAraucan\u00eda ilustrada, una loca geograf\u00eda\u201d, organizado por el PAR Explora de CONICYT LA Araucan\u00eda, ejecutado por la Universidad de La Frontera y el Museo Regional de La Araucan\u00eda. &nbsp; La actividad est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-2430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Son m\u00e1s de un centenar de estudiantes de La Araucan\u00eda, quienes&nbsp; ya han tenido la posibilidad de participar del entretenido y din\u00e1mico taller: \u201cAraucan\u00eda ilustrada, una loca geograf\u00eda\u201d, organizado por el PAR Explora de CONICYT LA Araucan\u00eda, ejecutado por la Universidad de La Frontera y el Museo Regional de La Araucan\u00eda. &nbsp; La actividad est\u00e1 [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:51:25+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda\",\"datePublished\":\"2017-09-28T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:51:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\"},\"wordCount\":606,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\",\"url\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\",\"name\":\"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg\",\"datePublished\":\"2017-09-28T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:51:25+00:00\",\"author\":{\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage\",\"url\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg\",\"contentUrl\":\"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explora.cl\/araucania\/#website\",\"url\":\"https:\/\/explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/","og_locale":"es_ES","og_type":"article","og_title":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda","og_description":"Son m\u00e1s de un centenar de estudiantes de La Araucan\u00eda, quienes&nbsp; ya han tenido la posibilidad de participar del entretenido y din\u00e1mico taller: \u201cAraucan\u00eda ilustrada, una loca geograf\u00eda\u201d, organizado por el PAR Explora de CONICYT LA Araucan\u00eda, ejecutado por la Universidad de La Frontera y el Museo Regional de La Araucan\u00eda. &nbsp; La actividad est\u00e1 [&hellip;]","og_url":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/","og_site_name":"Araucan\u00eda","article_published_time":"2017-09-28T04:00:00+00:00","article_modified_time":"2019-05-20T18:51:25+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#article","isPartOf":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/"},"author":{"name":"webman","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda","datePublished":"2017-09-28T04:00:00+00:00","dateModified":"2019-05-20T18:51:25+00:00","mainEntityOfPage":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/"},"wordCount":606,"commentCount":0,"image":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/","url":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/","name":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda - Araucan\u00eda","isPartOf":{"@id":"https:\/\/explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage"},"image":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage"},"thumbnailUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg","datePublished":"2017-09-28T04:00:00+00:00","dateModified":"2019-05-20T18:51:25+00:00","author":{"@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#primaryimage","url":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg","contentUrl":"https:\/\/explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/araucania.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/explora.cl\/araucania\/a-traves-de-la-ilustracion-estudiantes-conocen-las-32-comunas-de-la-araucania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"A trav\u00e9s de la ilustraci\u00f3n estudiantes conocen las 32 comunas de La Araucan\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/explora.cl\/araucania\/#website","url":"https:\/\/explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/2430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=2430"}],"version-history":[{"count":1,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/2430\/revisions"}],"predecessor-version":[{"id":37918,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/2430\/revisions\/37918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/media\/2431"}],"wp:attachment":[{"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=2430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=2430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=2430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}